 {"id":819,"date":"2026-07-27T22:26:00","date_gmt":"2026-07-27T22:26:00","guid":{"rendered":"https:\/\/institutoinae.com.br\/?p=819"},"modified":"2026-08-15T22:31:00","modified_gmt":"2026-08-15T22:31:00","slug":"inae-estreia-com-tres-barcos-na-53a-semana-internacional-de-vela-de-ilhabela","status":"publish","type":"post","link":"https:\/\/institutoinae.com.br\/index.php\/2026\/07\/27\/inae-estreia-com-tres-barcos-na-53a-semana-internacional-de-vela-de-ilhabela\/","title":{"rendered":"Ina\u00ea estreia com tr\u00eas barcos na 53\u00aa Semana Internacional de Vela de Ilhabela"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"582\" src=\"https:\/\/institutoinae.com.br\/wp-content\/uploads\/2026\/08\/Inae-50-1024x582.jpg\" alt=\"\" class=\"wp-image-820\" srcset=\"https:\/\/institutoinae.com.br\/wp-content\/uploads\/2026\/08\/Inae-50-1024x582.jpg 1024w, https:\/\/institutoinae.com.br\/wp-content\/uploads\/2026\/08\/Inae-50-300x171.jpg 300w, https:\/\/institutoinae.com.br\/wp-content\/uploads\/2026\/08\/Inae-50-768x437.jpg 768w, https:\/\/institutoinae.com.br\/wp-content\/uploads\/2026\/08\/Inae-50.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9ditos: Gabriela Petarnella\n<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">Fam\u00edlia Umbuzeiro se dividiu em tr\u00eas classes para as regatas Alcatrazes por Boreste e Toque-Toque por Boreste, neste domingo (26\/7)<\/h3>\n\n\n\n<p>O&nbsp;Ina\u00ea estreou na 53\u00aa Semana Internacional de Vela de Ilhabela neste domingo (26), marcando um momento especial do projeto. Com tr\u00eas barcos na raia, em tr\u00eas das principais classes de oceano, a fam\u00edlia Umbuzeiro enfrentou os desafios das regatas Alcatrazes por Boreste Marinha do Brasil e Toque Toque por Boreste, que abriram oficialmente a competi\u00e7\u00e3o.<\/p>\n\n\n\n<p>A regata Alcatrazes por Boreste Marinha do Brasil, com aproximadamente 55 milhas n\u00e1uticas,&nbsp; come\u00e7ou com vento sul dentro do Canal de S\u00e3o Sebasti\u00e3o.&nbsp;O vento rondou e diminuiu, exigindo uma boa estrat\u00e9gia das equipes participantes. Por fora do canal, quem conseguiu aproveitar o vento leste chegou antes a Alcatrazes, ganhando vantagem na disputa.&nbsp;<\/p>\n\n\n\n<p>Para os barcos da classe ORC, a disputa foi bem equilibrada, com muitas trocas de posi\u00e7\u00f5es e apenas uma hora de intervalo entre o primeiro e o \u00faltimo colocado. O Ina\u00ea Soto40 Transbrasa, sob o comando de Bayard Neto, fechou a regata com&nbsp;07h42min57 de dura\u00e7\u00e3o, em 19\u00ba.&nbsp;A vit\u00f3ria ficou com o uruguaio Lady, de Nicolas Gonzalez.<\/p>\n\n\n\n<p>&#8220;Foi um vento dif\u00edcil rondado e intermitente. Largamos com vento vindo de sul e depois pr\u00f3ximo \u00e0 Ponta da Sela um momento dif\u00edcil pela troca do Sul para Sudeste.&nbsp;Quem conseguiu entrar no leste antes se deu melhor e conseguiu abrir maior dist\u00e2ncia&#8221;, destacou o comandante Bayard Neto.<\/p>\n\n\n\n<p>O desafio foi mais duro para os barcos da C30, Bra-RGS C, RGS-Cruiser e Cl\u00e1ssicos, que disputaram a Regata Ilha de Toque-Toque por Boreste. O vento sul dentro do canal de S\u00e3o Sebasti\u00e3o rondou para nordeste e depois para leste, levando os veleiros a &#8220;ca\u00e7ar&#8221; a brisa, numa regata mais t\u00e9cnica e estrat\u00e9gica.&nbsp;<\/p>\n\n\n\n<p>O Rainha Ina\u00ea, comandado por Beto Umbuzeiro, fechou a regata em oitavo lugar na classe Bra-RGS, no tempo corrigido, com&nbsp;07h11min42. E o&nbsp;Ina\u00ea I, com o veterano Bayard Filho no comando aos 86 anos, completou a regata em d\u00e9cimo lugar no tempo corrigido, na RGS-Cruiser, com&nbsp;07h55min20.&nbsp;&nbsp;<\/p>\n\n\n\n<p>A abertura da 53\u00aa SIVI Daycoval contou mais uma vez com a participa\u00e7\u00e3o especial da Esquadrilha da Fuma\u00e7a, que realizou manobras a\u00e9reas durante o tradicional Desfile de Barcos e encantou o p\u00fablico de milhares de pessoas presentes no p\u00eder da Vila.&nbsp;A Fragata Tamandar\u00e9 F200, mais moderno navio de guerra da Marinha, tamb\u00e9m marcou presen\u00e7a na cerim\u00f4nia, antes da largada para a regata Alcatrazes.<\/p>\n\n\n\n<p><strong>Resultados das regatas de abertura&nbsp;<a href=\"https:\/\/viramos.com\/sivi53\">AQUI<\/a><\/strong><\/p>\n\n\n\n<p><strong>Fam\u00edlia Umbuzeiro<\/strong>&nbsp;<\/p>\n\n\n\n<p>A fam\u00edlia Umbuzeiro, um dos sobrenomes mais tradicionais da vela santista e do esporte n\u00e1utico brasileiro, inicia a temporada 2026 com um projeto ampliado e presen\u00e7a in\u00e9dita nas principais classes oce\u00e2nicas do pa\u00eds. Com quatro embarca\u00e7\u00f5es no calend\u00e1rio nacional, a equipe Ina\u00ea consolida sua expans\u00e3o e fortalece a atua\u00e7\u00e3o dentro das regatas realizadas no litoral paulista e nos principais campeonatos da modalidade.<\/p>\n\n\n\n<p>O novo ciclo ganhou impulso com a aprova\u00e7\u00e3o do patroc\u00ednio do Porto de Santos, via Lei de Incentivo ao Esporte, ao Ina\u00ea Soto40, embarca\u00e7\u00e3o da classe ORC comandada por Bayard Umbuzeiro Neto. Al\u00e9m disso, o barco tamb\u00e9m conta com o patroc\u00ednio da Eldorado Brasil.<\/p>\n\n\n\n<p><strong>Ina\u00ea e o Porto de Santos<\/strong><\/p>\n\n\n\n<p>O Ina\u00ea Soto40 Transbrasa conta com o apoio do Porto de Santos, por meio da Lei de Incentivo ao Esporte. O Porto de Santos \u00e9 o maior complexo portu\u00e1rio da Am\u00e9rica Latina e refer\u00eancia nacional em desenvolvimento, log\u00edstica e conex\u00e3o do Brasil com o mundo. Onde tem patroc\u00ednio, tem Governo do Brasil.<\/p>\n\n\n\n<p><strong>SOBRE A ELDORADO BRASIL<\/strong><\/p>\n\n\n\n<p>A Eldorado Brasil Celulose, empresa do Grupo J&amp;F, \u00e9 reconhecida globalmente por sua&nbsp;excel\u00eancia operacional e seu compromisso com a sustentabilidade, resultado do trabalho&nbsp;de uma equipe qualificada de mais de 5 mil colaboradores. Inovadora no manejo florestal&nbsp;e na fabrica\u00e7\u00e3o de celulose, produz 1,8 milh\u00e3o de toneladas de celulose de alta qualidade&nbsp;por ano, atendendo aos mais exigentes padr\u00f5es e certifica\u00e7\u00f5es do mercado internacional.&nbsp;Seu complexo industrial em Tr\u00eas Lagoas (MS) tamb\u00e9m tem capacidade para gerar energia&nbsp;renov\u00e1vel para abastecer uma cidade de 2,1 milh\u00f5es de habitantes. Em Santos (SP), opera&nbsp;o EBLog, um dos mais modernos terminais portu\u00e1rios da Am\u00e9rica Latina, exportando o&nbsp;produto para mais de 40 pa\u00edses. A Companhia mant\u00e9m um forte compromisso com a&nbsp;sustentabilidade, inova\u00e7\u00e3o, competitividade e valoriza\u00e7\u00e3o das pessoas.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img decoding=\"async\" width=\"1024\" height=\"253\" src=\"https:\/\/institutoinae.com.br\/wp-content\/uploads\/2026\/08\/Defeso-1-1024x253.png\" alt=\"\" class=\"wp-image-814\" style=\"width:903px;height:auto\" srcset=\"https:\/\/institutoinae.com.br\/wp-content\/uploads\/2026\/08\/Defeso-1-1024x253.png 1024w, https:\/\/institutoinae.com.br\/wp-content\/uploads\/2026\/08\/Defeso-1-300x74.png 300w, https:\/\/institutoinae.com.br\/wp-content\/uploads\/2026\/08\/Defeso-1-768x190.png 768w, https:\/\/institutoinae.com.br\/wp-content\/uploads\/2026\/08\/Defeso-1.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fam\u00edlia Umbuzeiro se dividiu em tr\u00eas classes para as regatas Alcatrazes por Boreste e Toque-Toque por Boreste, neste domingo (26\/7) O&nbsp;Ina\u00ea estreou na 53\u00aa Semana Internacional de Vela de Ilhabela neste domingo (26), marcando um momento especial do projeto. Com tr\u00eas barcos na raia, em tr\u00eas das principais classes de oceano, a fam\u00edlia Umbuzeiro enfrentou [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":820,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[18,2],"tags":[],"class_list":["post-819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes","category-news"],"blocksy_meta":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/institutoinae.com.br\/index.php\/wp-json\/wp\/v2\/posts\/819"}],"collection":[{"href":"https:\/\/institutoinae.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/institutoinae.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/institutoinae.com.br\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/institutoinae.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=819"}],"version-history":[{"count":1,"href":"https:\/\/institutoinae.com.br\/index.php\/wp-json\/wp\/v2\/posts\/819\/revisions"}],"predecessor-version":[{"id":821,"href":"https:\/\/institutoinae.com.br\/index.php\/wp-json\/wp\/v2\/posts\/819\/revisions\/821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/institutoinae.com.br\/index.php\/wp-json\/wp\/v2\/media\/820"}],"wp:attachment":[{"href":"https:\/\/institutoinae.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/institutoinae.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/institutoinae.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}