 {"id":828,"date":"2026-06-08T22:36:00","date_gmt":"2026-06-08T22:36:00","guid":{"rendered":"https:\/\/institutoinae.com.br\/?p=828"},"modified":"2026-08-15T22:44:51","modified_gmt":"2026-08-15T22:44:51","slug":"inae-une-geracoes-da-familia-umbuzeiro-e-conquista-podio-na-6a-regata-ubatuba-ilhabela","status":"publish","type":"post","link":"https:\/\/institutoinae.com.br\/index.php\/2026\/06\/08\/inae-une-geracoes-da-familia-umbuzeiro-e-conquista-podio-na-6a-regata-ubatuba-ilhabela\/","title":{"rendered":"Ina\u00ea une gera\u00e7\u00f5es da fam\u00edlia Umbuzeiro e conquista p\u00f3dio na 6\u00aa Regata Ubatuba-Ilhabela"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"582\" src=\"https:\/\/institutoinae.com.br\/wp-content\/uploads\/2026\/08\/Innae-1-na-6a-Regata-Ubatuba-Ilhabela-1024x582.jpg\" alt=\"\" class=\"wp-image-829\" srcset=\"https:\/\/institutoinae.com.br\/wp-content\/uploads\/2026\/08\/Innae-1-na-6a-Regata-Ubatuba-Ilhabela-1024x582.jpg 1024w, https:\/\/institutoinae.com.br\/wp-content\/uploads\/2026\/08\/Innae-1-na-6a-Regata-Ubatuba-Ilhabela-300x171.jpg 300w, https:\/\/institutoinae.com.br\/wp-content\/uploads\/2026\/08\/Innae-1-na-6a-Regata-Ubatuba-Ilhabela-768x437.jpg 768w, https:\/\/institutoinae.com.br\/wp-content\/uploads\/2026\/08\/Innae-1-na-6a-Regata-Ubatuba-Ilhabela.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9ditos: Fred Hoffmann\n<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">Barco da classe RGS-Cruiser foi o vice-campe\u00e3o na prova de percurso In Port, no s\u00e1bado (6\/6) e garantiu o 4o lugar na travessia principal, na sexta (5\/6)<\/h3>\n\n\n\n<p>A 6\u00aa Regata Ubatuba-Ilhabela proporcionou um momento especial para a fam\u00edlia Umbuzeiro. Com&nbsp;duas gera\u00e7\u00f5es reunidas a bordo do Ina\u00ea 1, o tradicional &#8220;50t\u00e3o&#8221;, a equipe conquistou o quarto lugar na travessia Ubatuba-Ilhabela, na sexta-feira (5), e o vice-campeonato da classe RGS-Cruiser A na regata In Port, disputada no s\u00e1bado (6).<\/p>\n\n\n\n<p>O Ina\u00ea 1 teve&nbsp;Bayard Umbuzeiro Filho no comando, acompanhado pela esposa Ana Helena, pelos filhos e pela nora. Uma forma\u00e7\u00e3o rara que transformou a competi\u00e7\u00e3o em uma celebra\u00e7\u00e3o da hist\u00f3ria de uma fam\u00edlia que dedica sua vida ao mar h\u00e1 d\u00e9cadas.<\/p>\n\n\n\n<p>A edi\u00e7\u00e3o deste ano da Regata Ubatuba-Ilhabela reuniu 69 embarca\u00e7\u00f5es das classes ORC, BRA-RGS, RGS-Cruiser, Cl\u00e1ssicos e Multicasco. O evento teve dois dias de disputas.&nbsp;<\/p>\n\n\n\n<p>Na sexta-feira (5), os competidores enfrentaram uma travessia de 25 milhas n\u00e1uticas, cerca de 45 quil\u00f4metros, entre Ubatuba e Ilhabela. Os ventos fracos exigiram paci\u00eancia, estrat\u00e9gia e precis\u00e3o das tripula\u00e7\u00f5es.&nbsp;No s\u00e1bado (6), as embarca\u00e7\u00f5es voltaram \u00e0 \u00e1gua para a disputa da regata In Port, realizada em circuito fechado no Canal de S\u00e3o Sebasti\u00e3o.&nbsp;<\/p>\n\n\n\n<p>&#8220;Eu j\u00e1 velejei pensando em competi\u00e7\u00e3o, em performance, como o meu filho Bayard no Soto40, mas hoje estou mais light. Nem sempre a gente ganha a regata, mas a participa\u00e7\u00e3o \u00e9 fundamental. E a gente est\u00e1 sempre evoluindo&#8221;, afirmou o comandante Bayard Umbuzeiro Filho.&nbsp;<\/p>\n\n\n\n<p>Veterano, Bayard Filho acumula mais de tr\u00eas d\u00e9cadas de participa\u00e7\u00e3o nas principais regatas do calend\u00e1rio nacional, sempre \u00e0 frente do Ina\u00ea 1, um Jenneau 50 que \u00e9 um dos barcos mais tradicionais da flotilha brasileira. Tamb\u00e9m ganhou destaque nos torneios regionais e nacionais de pesca oce\u00e2nica, na d\u00e9cada de 60.&nbsp;<\/p>\n\n\n\n<p>A paix\u00e3o pelos esportes n\u00e1uticos come\u00e7ou ainda nas pranchas de surfe. Depois vieram os catamar\u00e3s da classe Hobie Cat e, posteriormente, a vela oce\u00e2nica. Ao longo dessa trajet\u00f3ria, a fam\u00edlia construiu uma hist\u00f3ria marcada por conquistas e pela forte liga\u00e7\u00e3o com o oceano.<\/p>\n\n\n\n<p>O comandante destacou ainda o prazer de dividir o barco com toda a fam\u00edlia:&nbsp;&#8220;Velejar com toda a fam\u00edlia j\u00e1 foi um pouco mais estressante. Hoje, com o amadurecimento de todo mundo, ficou muito mais light. Tem sido muito bom.&#8221;<\/p>\n\n\n\n<p>Entre os tripulantes estava tamb\u00e9m Bayard Umbuzeiro Neto, comandante do Ina\u00ea Soto40 Transbrasa e atual comodoro da Associa\u00e7\u00e3o Brasileira de Veleiros de Oceano (ABVO). Acostumado \u00e0s disputas de alto rendimento da classe ORC, ele atuou como t\u00e1tico do Ina\u00ea 1 durante a competi\u00e7\u00e3o.<\/p>\n\n\n\n<p>&#8220;H\u00e1 muito tempo eu n\u00e3o sentia esse prazer de velejar em fam\u00edlia, com meu pai, meu irm\u00e3o, minha cunhada e a Ana Helena. Foi uma travessia sem estresse, muito gostosa. Tenho velejado mais na ORC, de Soto40, onde existe uma cobran\u00e7a constante por resultados. Hoje, velejando neste barco que j\u00e1 foi de performance e agora est\u00e1 equipado para cruzeiro, foi um prazer estar aqui fazendo uma boa regata&#8221;, destacou.<\/p>\n\n\n\n<p>Mais do que os resultados, o fim de semana refor\u00e7ou uma das principais caracter\u00edsticas do projeto Ina\u00ea: a capacidade de unir tradi\u00e7\u00e3o, fam\u00edlia e paix\u00e3o pelo oceano, gera\u00e7\u00e3o ap\u00f3s gera\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Resultados \u2013 Travessia Ubatuba-Ilhabela (RGS-Cruiser A)<\/strong><\/p>\n\n\n\n<p>1\u00ba Kon Tiki (Michael Downey) \u2013 3h46min14s<br>2\u00ba Kaup\u00ea (Pedro Macedo) \u2013 3h48min05s<br>3\u00ba Pura Vida (Marcos de Oliveira Cesar) \u2013 3h54min10s<br>4\u00ba Ina\u00ea 1 (Bayard Umbuzeiro Filho) \u2013 3h55min23s<\/p>\n\n\n\n<p><strong>Resultados \u2013 Regata In Port (RGS-Cruiser A)<\/strong><\/p>\n\n\n\n<p>1\u00ba Blue Wind (James Beline) \u2013 58min34s<br>2\u00ba Ina\u00ea 1 (Bayard Umbuzeiro Filho) \u2013 1h00min27s<br>3\u00ba Kaup\u00ea (Pedro Macedo) \u2013 1h02min52s<\/p>\n\n\n\n<p><strong>Ina\u00ea Soto na Copa Mitsubishi<\/strong><\/p>\n\n\n\n<p>A equipe Ina\u00ea volta \u00e0 raia de Ilhabela neste final de semana (13 e 14 de junho). O Ina\u00ea Soto40 Transbrasa disputar\u00e1 a segunda etapa da Copa Mitsubishi na classe ORC, sob o comando de Bayard Umbuzeiro Neto. O barco estreou na temporada 2026 com o patroc\u00ednio do Porto de Santos, por meio da Lei de Incentivo ao Esporte, e est\u00e1 na vice-lideran\u00e7a do circuito oce\u00e2nico. Onde tem patroc\u00ednio, tem Governo do Brasil.<\/p>\n\n\n\n<p><strong>Sobre o Ina\u00ea<\/strong><\/p>\n\n\n\n<p>O projeto Ina\u00ea re\u00fane quatro embarca\u00e7\u00f5es que competem nas principais classes da vela oce\u00e2nica brasileira: o Soto40 Transbrasa, o Ina\u00ea 1 (Jeanneau 50DS), um Range 26 e um HPE25. Com ra\u00edzes em Santos (SP), a equipe \u00e9 formada pela fam\u00edlia Umbuzeiro e representa uma tradi\u00e7\u00e3o constru\u00edda ao longo de d\u00e9cadas de liga\u00e7\u00e3o com o mar.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"253\" src=\"https:\/\/institutoinae.com.br\/wp-content\/uploads\/2026\/08\/Defeso-1-1024x253.png\" alt=\"\" class=\"wp-image-814\" srcset=\"https:\/\/institutoinae.com.br\/wp-content\/uploads\/2026\/08\/Defeso-1-1024x253.png 1024w, https:\/\/institutoinae.com.br\/wp-content\/uploads\/2026\/08\/Defeso-1-300x74.png 300w, https:\/\/institutoinae.com.br\/wp-content\/uploads\/2026\/08\/Defeso-1-768x190.png 768w, https:\/\/institutoinae.com.br\/wp-content\/uploads\/2026\/08\/Defeso-1.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Barco da classe RGS-Cruiser foi o vice-campe\u00e3o na prova de percurso In Port, no s\u00e1bado (6\/6) e garantiu o 4o lugar na travessia principal, na sexta (5\/6) A 6\u00aa Regata Ubatuba-Ilhabela proporcionou um momento especial para a fam\u00edlia Umbuzeiro. Com&nbsp;duas gera\u00e7\u00f5es reunidas a bordo do Ina\u00ea 1, o tradicional &#8220;50t\u00e3o&#8221;, a equipe conquistou o quarto [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":829,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[18,2],"tags":[],"class_list":["post-828","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes","category-news"],"blocksy_meta":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/institutoinae.com.br\/index.php\/wp-json\/wp\/v2\/posts\/828"}],"collection":[{"href":"https:\/\/institutoinae.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/institutoinae.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/institutoinae.com.br\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/institutoinae.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=828"}],"version-history":[{"count":1,"href":"https:\/\/institutoinae.com.br\/index.php\/wp-json\/wp\/v2\/posts\/828\/revisions"}],"predecessor-version":[{"id":830,"href":"https:\/\/institutoinae.com.br\/index.php\/wp-json\/wp\/v2\/posts\/828\/revisions\/830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/institutoinae.com.br\/index.php\/wp-json\/wp\/v2\/media\/829"}],"wp:attachment":[{"href":"https:\/\/institutoinae.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/institutoinae.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/institutoinae.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}